{"id":122,"date":"2025-01-12T22:06:53","date_gmt":"2025-01-12T22:06:53","guid":{"rendered":"https:\/\/photo.michelschmidlin.com\/?page_id=122"},"modified":"2025-05-06T21:08:05","modified_gmt":"2025-05-06T21:08:05","slug":"personal","status":"publish","type":"page","link":"https:\/\/michelschmidlin.com\/de\/personal\/","title":{"rendered":"Personal"},"content":{"rendered":"\n<p class=\"has-text-align-center is-style-text-display is-style-text-display--1 wp-block-paragraph\"><a href=\"https:\/\/michelschmidlin.com\/landscapes\/\" data-type=\"page\" data-id=\"150\">Landscapes<\/a><\/p>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/landscapes\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2024\/12\/I7A2799-3-1024x683.jpg\" alt=\"\" class=\"wp-image-34\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2024\/12\/I7A2799-3-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2024\/12\/I7A2799-3-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2024\/12\/I7A2799-3-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2024\/12\/I7A2799-3-1536x1025.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2024\/12\/I7A2799-3-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/landscapes\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/012_Lake-long-gone-Potosi-Bolivia-1024x682.jpg\" alt=\"\" class=\"wp-image-236\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/012_Lake-long-gone-Potosi-Bolivia-1024x682.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/012_Lake-long-gone-Potosi-Bolivia-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/012_Lake-long-gone-Potosi-Bolivia-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/012_Lake-long-gone-Potosi-Bolivia-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/012_Lake-long-gone-Potosi-Bolivia-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/landscapes\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/004_Mont-Avril-Canton-of-Valais-Switzerland-1024x683.jpg\" alt=\"\" class=\"wp-image-423\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/004_Mont-Avril-Canton-of-Valais-Switzerland-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/004_Mont-Avril-Canton-of-Valais-Switzerland-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/004_Mont-Avril-Canton-of-Valais-Switzerland-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/004_Mont-Avril-Canton-of-Valais-Switzerland-1536x1025.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/004_Mont-Avril-Canton-of-Valais-Switzerland-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:120px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center is-style-text-display is-style-text-display--2 wp-block-paragraph\"><a href=\"https:\/\/michelschmidlin.com\/wildlife\/\" data-type=\"page\" data-id=\"1241\">Wildlife<\/a><\/p>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/wildlife\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/028_Black-capped-squirrel-monkey-Bolivianischer-Totenkopfaffe-Samiri-boliviensis-Bolivia-1024x683.jpg\" alt=\"\" class=\"wp-image-482\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/028_Black-capped-squirrel-monkey-Bolivianischer-Totenkopfaffe-Samiri-boliviensis-Bolivia-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/028_Black-capped-squirrel-monkey-Bolivianischer-Totenkopfaffe-Samiri-boliviensis-Bolivia-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/028_Black-capped-squirrel-monkey-Bolivianischer-Totenkopfaffe-Samiri-boliviensis-Bolivia-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/028_Black-capped-squirrel-monkey-Bolivianischer-Totenkopfaffe-Samiri-boliviensis-Bolivia-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/028_Black-capped-squirrel-monkey-Bolivianischer-Totenkopfaffe-Samiri-boliviensis-Bolivia-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/wildlife\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/016_Hyacinth-macaw-Hyazinth-Ara-Anodorhynchus-hyacinthinus-Brazil-1024x683.jpg\" alt=\"\" class=\"wp-image-453\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/016_Hyacinth-macaw-Hyazinth-Ara-Anodorhynchus-hyacinthinus-Brazil-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/016_Hyacinth-macaw-Hyazinth-Ara-Anodorhynchus-hyacinthinus-Brazil-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/016_Hyacinth-macaw-Hyazinth-Ara-Anodorhynchus-hyacinthinus-Brazil-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/016_Hyacinth-macaw-Hyazinth-Ara-Anodorhynchus-hyacinthinus-Brazil-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/016_Hyacinth-macaw-Hyazinth-Ara-Anodorhynchus-hyacinthinus-Brazil-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/wildlife\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/027_Andean-fox-Andenschakal-Lycalopex-culpaeus-1024x683.jpg\" alt=\"\" class=\"wp-image-481\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/027_Andean-fox-Andenschakal-Lycalopex-culpaeus-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/027_Andean-fox-Andenschakal-Lycalopex-culpaeus-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/027_Andean-fox-Andenschakal-Lycalopex-culpaeus-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/027_Andean-fox-Andenschakal-Lycalopex-culpaeus-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/027_Andean-fox-Andenschakal-Lycalopex-culpaeus-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:120px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center is-style-text-display is-style-text-display--3 wp-block-paragraph\"><a href=\"https:\/\/michelschmidlin.com\/journeys\/\" data-type=\"page\" data-id=\"155\">Journeys<\/a><\/p>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/journeys\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/009_Imressions-NA14-1024x683.jpg\" alt=\"\" class=\"wp-image-492\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/009_Imressions-NA14-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/009_Imressions-NA14-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/009_Imressions-NA14-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/009_Imressions-NA14-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/009_Imressions-NA14-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/michelschmidlin.com\/journeys\/\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1709\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/018_Crossing-rivers-in-Patagonia-c-Tomas-Munita.avif\" alt=\"\" class=\"wp-image-1315\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/018_Crossing-rivers-in-Patagonia-c-Tomas-Munita.avif 2560w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/018_Crossing-rivers-in-Patagonia-c-Tomas-Munita-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/018_Crossing-rivers-in-Patagonia-c-Tomas-Munita-1024x684.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/018_Crossing-rivers-in-Patagonia-c-Tomas-Munita-768x513.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/018_Crossing-rivers-in-Patagonia-c-Tomas-Munita-1536x1025.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/018_Crossing-rivers-in-Patagonia-c-Tomas-Munita-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/michelschmidlin.com\/journeys\/\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/026_Parque-Nacional-Tres-Cruces.avif\" alt=\"\" class=\"wp-image-1323\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/026_Parque-Nacional-Tres-Cruces.avif 2560w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/026_Parque-Nacional-Tres-Cruces-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/026_Parque-Nacional-Tres-Cruces-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/026_Parque-Nacional-Tres-Cruces-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/026_Parque-Nacional-Tres-Cruces-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/02\/026_Parque-Nacional-Tres-Cruces-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:120px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center is-style-text-display is-style-text-display--4 wp-block-paragraph\"><a href=\"https:\/\/michelschmidlin.com\/projects\/\" data-type=\"page\" data-id=\"158\">Projects<\/a><\/p>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/projects\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Homo-technologicus_007-1024x683.jpg\" alt=\"\" class=\"wp-image-1096\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Homo-technologicus_007-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Homo-technologicus_007-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Homo-technologicus_007-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Homo-technologicus_007-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Homo-technologicus_007-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/projects\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Power_006-1024x683.jpg\" alt=\"\" class=\"wp-image-1075\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Power_006-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Power_006-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Power_006-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Power_006-1536x1025.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/Power_006-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/michelschmidlin.com\/projects\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/For-Winter-Use-Only_008-1024x683.jpg\" alt=\"\" class=\"wp-image-1108\" srcset=\"https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/For-Winter-Use-Only_008-1024x683.jpg 1024w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/For-Winter-Use-Only_008-300x200.jpg 300w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/For-Winter-Use-Only_008-768x512.jpg 768w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/For-Winter-Use-Only_008-1536x1024.jpg 1536w, https:\/\/michelschmidlin.com\/wp-content\/uploads\/2025\/01\/For-Winter-Use-Only_008-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Landscapes Wildlife Journeys Projects<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":98,"footnotes":""},"class_list":["post-122","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/pages\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":24,"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/pages\/122\/revisions"}],"predecessor-version":[{"id":1515,"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/pages\/122\/revisions\/1515"}],"wp:attachment":[{"href":"https:\/\/michelschmidlin.com\/de\/wp-json\/wp\/v2\/media?parent=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}